{"id":4986,"date":"2023-04-02T16:43:26","date_gmt":"2023-04-02T14:43:26","guid":{"rendered":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1.jpg"},"modified":"2023-04-02T16:43:26","modified_gmt":"2023-04-02T14:43:26","slug":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-2","status":"inherit","type":"attachment","link":"https:\/\/oswiataberlin.de\/de\/wielkanoc-2023\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-2\/","title":{"rendered":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-4986","attachment","type-attachment","status-inherit","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"de","enabled_languages":["pl","de"],"languages":{"pl":{"title":true},"de":{"title":false}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-225x300.jpg 225w, https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-700x933.jpg 700w, https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-410x547.jpg 410w, https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-100x133.jpg 100w, https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-275x367.jpg 275w, https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-370x493.jpg 370w, https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1.jpg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":768,"height":1024,"file":"2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1.jpg","sizes":{"medium":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-225x300.jpg"},"thumbnail":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-150x150.jpg"},"rocked-large-thumb":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-700x933.jpg","width":700,"height":933,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-700x933.jpg"},"rocked-medium-thumb":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-410x547.jpg","width":410,"height":547,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-410x547.jpg"},"rocked-small-thumb":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-100x133.jpg","width":100,"height":133,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-100x133.jpg"},"rocked-client-thumb":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-275x367.jpg","width":275,"height":367,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-275x367.jpg"},"trx_addons-thumb-huge":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-768x658.jpg","width":768,"height":658,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-768x658.jpg"},"trx_addons-thumb-big":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-768x433.jpg","width":768,"height":433,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-768x433.jpg"},"trx_addons-thumb-medium":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-370x208.jpg","width":370,"height":208,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-370x208.jpg"},"trx_addons-thumb-small":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-270x152.jpg","width":270,"height":152,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-270x152.jpg"},"trx_addons-thumb-portrait":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-370x493.jpg","width":370,"height":493,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-370x493.jpg"},"trx_addons-thumb-avatar":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-370x370.jpg","width":370,"height":370,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-370x370.jpg"},"trx_addons-thumb-tiny":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-75x75.jpg","width":75,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-75x75.jpg"},"trx_addons-thumb-masonry":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-370x493.jpg","width":370,"height":493,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1-370x493.jpg"},"full":{"file":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":4939,"source_url":"https:\/\/oswiataberlin.de\/wp-content\/uploads\/2023\/04\/d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1.jpg","filename":"d8a2d6b5-3f8e-4c6e-bef7-b06964fdc4e2-1.jpg","filesize":111828,"_links":{"self":[{"href":"https:\/\/oswiataberlin.de\/de\/wp-json\/wp\/v2\/media\/4986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oswiataberlin.de\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/oswiataberlin.de\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/oswiataberlin.de\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/oswiataberlin.de\/de\/wp-json\/wp\/v2\/comments?post=4986"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":4939,"href":"https:\/\/oswiataberlin.de\/de\/wp-json\/wp\/v2\/posts\/4939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}